{"id":2,"date":"2026-09-01T21:11:36","date_gmt":"2026-09-02T02:11:36","guid":{"rendered":"https:\/\/ikonodesing.com\/?page_id=2"},"modified":"2026-09-01T21:11:36","modified_gmt":"2026-09-02T02:11:36","slug":"pagina-ejemplo","status":"publish","type":"page","link":"https:\/\/ikonodesing.com\/index.php\/pagina-ejemplo\/","title":{"rendered":"P\u00e1gina de ejemplo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta es una p\u00e1gina de ejemplo. Es diferente de una entrada de blog porque se quedar\u00e1 en ese lugar y se mostrar\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de la gente comienza con una p\u00e1gina de acerca de que los introduce a los visitantes potenciales del sitio. Podr\u00eda decir algo como esto:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p class=\"wp-block-paragraph\">\u00a1Hola! Soy un Mensajero en bici durante el d\u00eda, aspirante a actor de noche, y este es mi sitio Web. Vivo en los \u00c1ngeles, tengo un gran perro llamado Jack, y me gustan las pi\u00f1as coladas. (Y estar atrapados en la lluvia.)<\/p>\n\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026o algo as\u00ed:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p class=\"wp-block-paragraph\">La Empresa Doohickey XYZ fue fundada en 1971, y ha estado proporcionando cosas de calidad al p\u00fablico desde entonces. Ubicado en la ciudad de Gotham, XYZ emplea a m\u00e1s de 2.000 personas y hace todo tipo de cosas impresionantes para la comunidad g\u00f3tica.<\/p>\n\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Como nuevo usuario de WordPress, debes ir a <a href=\"https:\/\/ikonodesing.com\/wp-admin\/\">tu Escritorio<\/a> para eliminar esta p\u00e1gina, y as\u00ed crear nuevas p\u00e1ginas para su contenido. \u00a1Que te diviertas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta es una p\u00e1gina de ejemplo. Es diferente de una entrada de blog porque se quedar\u00e1 en ese lugar y se mostrar\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de la gente comienza con una p\u00e1gina de acerca de que los introduce a los visitantes potenciales del sitio. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/ikonodesing.com\/index.php\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikonodesing.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ikonodesing.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ikonodesing.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ikonodesing.com\/index.php\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/ikonodesing.com\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/ikonodesing.com\/index.php\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}